{"id":17621,"date":"2021-10-02T17:54:47","date_gmt":"2021-10-02T15:54:47","guid":{"rendered":"https:\/\/antecscientific.com\/diagnostica\/vitamine\/"},"modified":"2025-09-09T12:49:38","modified_gmt":"2025-09-09T10:49:38","slug":"vitamine","status":"publish","type":"page","link":"https:\/\/antecscientific.com\/it\/applicazioni\/diagnostica\/vitamine\/","title":{"rendered":"Vitamine"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Header&#8221; _builder_version=&#8221;4.16&#8243; background_image=&#8221;https:\/\/antecscientific.com\/wp-content\/uploads\/2020\/10\/application_vitamins.jpg&#8221; parallax=&#8221;on&#8221; custom_padding=&#8221;2vw|0px|200px|0px|false|false&#8221; collapsed=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Breadcrumbs (don&#8217;t touch)&#8221; _builder_version=&#8221;4.16&#8243; text_font=&#8221;|700|||||||&#8221; text_text_color=&#8221;#ffffff&#8221; text_font_size=&#8221;15px&#8221; link_font=&#8221;|700|||||||&#8221; link_text_color=&#8221;#ffffff&#8221; link_font_size=&#8221;15px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_text][et_pb_text admin_label=&#8221;Big page title (don&#8217;t touch)&#8221; _builder_version=&#8221;4.16&#8243; _dynamic_attributes=&#8221;content&#8221; text_font=&#8221;||||||||&#8221; header_font=&#8221;|700|||||||&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;80px&#8221; header_line_height=&#8221;1.2em&#8221; header_5_font=&#8221;Raleway|700||on|||||&#8221; header_5_text_color=&#8221;#000000&#8243; header_5_font_size=&#8221;20px&#8221; header_5_letter_spacing=&#8221;0.5em&#8221; header_5_line_height=&#8221;1.8em&#8221; animation_style=&#8221;zoom&#8221; animation_intensity_zoom=&#8221;5%&#8221; header_font_size_tablet=&#8221;48px&#8221; header_font_size_phone=&#8221;32px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; header_5_font_size_tablet=&#8221;14px&#8221; header_5_font_size_phone=&#8221;12px&#8221; header_5_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;]@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF90aXRsZSIsInNldHRpbmdzIjp7ImJlZm9yZSI6IjxoMT4iLCJhZnRlciI6IjxcL2gxPiJ9fQ==@[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Content&#8221; _builder_version=&#8221;4.16&#8243; background_color=&#8221;#ffffff&#8221; max_width=&#8221;90%&#8221; max_width_tablet=&#8221;&#8221; max_width_phone=&#8221;100%&#8221; max_width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;-160px||0px||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; border_color_all=&#8221;#ffffff&#8221; border_width_left=&#8221;10vw&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;2_3,1_3&#8243; custom_padding_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.16&#8243; width=&#8221;auto&#8221; max_width=&#8221;none&#8221; custom_padding=&#8221;27px|0|27px|0px|false|false&#8221; custom_padding_tablet=&#8221;|0px||0px||true&#8221; custom_padding_phone=&#8221;|10%||0px|false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Subtitle&#8221; _builder_version=&#8221;4.16&#8243; text_font=&#8221;||||||||&#8221; text_line_height=&#8221;2em&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;|600||on|||||&#8221; header_2_text_color=&#8221;#df0834&#8243; header_2_font_size=&#8221;20px&#8221; header_2_line_height=&#8221;1.4em&#8221; header_6_font=&#8221;|700||on|||||&#8221; header_6_font_size=&#8221;16px&#8221; header_6_letter_spacing=&#8221;5px&#8221; header_6_line_height=&#8221;1.8em&#8221; max_width=&#8221;700px&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; header_2_font_size_tablet=&#8221;25px&#8221; header_2_font_size_phone=&#8221;25px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Vitamine<\/h2>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Paragraph&#8221; _builder_version=&#8221;4.16&#8243; text_font=&#8221;||||||||&#8221; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;2em&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Raleway|700|||||||&#8221; header_2_font_size=&#8221;50px&#8221; header_2_line_height=&#8221;1.4em&#8221; header_6_font=&#8221;Raleway|700||on|||||&#8221; header_6_font_size=&#8221;16px&#8221; header_6_letter_spacing=&#8221;5px&#8221; header_6_line_height=&#8221;1.8em&#8221; text_orientation=&#8221;justified&#8221; max_width=&#8221;700px&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;0px||||false|false&#8221; custom_padding=&#8221;0px||||false|false&#8221; header_2_font_size_tablet=&#8221;35px&#8221; header_2_font_size_phone=&#8221;25px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; text_orientation_tablet=&#8221;&#8221; text_orientation_phone=&#8221;left&#8221; text_orientation_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>&nbsp;<\/p>\n<ul class=\"groot\">\n<li>Vitamine liposolubili A, D, E e K<\/li>\n<li>Vitamina C nel plasma<\/li>\n<li>Q10 e ubiquinoli<\/li>\n<li>Doppia cella, per la preriduzione (Vit K, Q10)<\/li>\n<li>HyREF senza manutenzione<\/li>\n<\/ul>\n<p>Le vitamine A, D, E e K appartengono alle vitamine liposolubili. Queste vitamine sono coinvolte in diversi processi biochimici dell&#8217;organismo. Anche la vitamina C idrosolubile \u00e8 coinvolta in una serie di reazioni enzimatiche e di sintesi del collagene. L&#8217;analisi delle vitamine non si limita agli alimenti e ai cosmetici, ma anche ai fluidi corporei per scoprire le malattie in fase iniziale.<\/p>\n<p>La vitamina C (acido ascorbico, AA) \u00e8 normalmente presente nel plasma e nei tessuti umani e animali. Il fabbisogno giornaliero \u00e8 considerato di almeno 70 mg e i livelli ematici normali sono compresi tra 28 e 85 \u03bcM. Ad esempio, l&#8217;analisi dell&#8217;AA nel plasma di pazienti geriatrici riflette la qualit\u00e0 dello stato di alimentazione di tali pazienti. L&#8217;analisi con LCEC \u00e8 molto semplice e altamente riproducibile con l&#8217;uso di idrochinone come standard interno e DTT per stabilizzare gli AA labili.<\/p>\n<p>Gli analizzatori di vitamine ALEXYS sono stati ottimizzati per soddisfare i requisiti di massima sensibilit\u00e0 in HPLC con rilevamento EC. Indipendentemente dalla matrice del campione, ALEXYS offre un metodo comodo e affidabile per le analisi di routine. Le soluzioni di sistema Antec includono tutte le parti e i prodotti chimici necessari per far funzionare la vostra analisi.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;5%|5%|||false|false&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/antecscientific.com\/wp-content\/uploads\/2025\/08\/ALEXYS_1p_EliteStSt_HQ_light_S.png-225&#215;300.webp&#8221; title_text=&#8221;ALEXYS_1p_EliteSt_HQ_light_S.png&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Download Table&#8221; _builder_version=&#8221;4.27.2&#8243; background_enable_color=&#8221;off&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;#f6f9fb 50%|#ffffff 100%&#8221; background_color_gradient_start=&#8221;#f6f9fb&#8221; background_color_gradient_start_position=&#8221;50%&#8221; background_color_gradient_end=&#8221;#ffffff&#8221; max_width=&#8221;100%&#8221; max_width_tablet=&#8221;&#8221; max_width_phone=&#8221;100%&#8221; max_width_last_edited=&#8221;on|desktop&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;0px||0px||false|false&#8221; custom_padding=&#8221;40px||40px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.27.2&#8243; background_color=&#8221;rgba(0,0,0,0)&#8221; width_tablet=&#8221;&#8221; width_phone=&#8221;&#8221; width_last_edited=&#8221;on|phone&#8221; max_width=&#8221;80%&#8221; max_width_tablet=&#8221;&#8221; max_width_phone=&#8221;&#8221; max_width_last_edited=&#8221;on|phone&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_text admin_label=&#8221;Shortcode of Table&#8221; _builder_version=&#8221;4.27.2&#8243; background_color=&#8221;#ffffff&#8221; max_width=&#8221;1200px&#8221; custom_padding=&#8221;20px|30px|30px|30px|false|false&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;|0px||0px|false|false&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; module_alignment_tablet=&#8221;&#8221; module_alignment_phone=&#8221;&#8221; module_alignment_last_edited=&#8221;on|desktop&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_blur=&#8221;40px&#8221; box_shadow_color=&#8221;rgba(0,33,91,0.17)&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Download<\/h3>\n<p>&nbsp;<\/p>\n        <div class=\"antec-downloads view--list\">\n        <div class=\"list-item name thead\">Name<\/div>\n        <div class=\"list-item rev thead\">Doc#<\/div>\n        <div class=\"list-item size thead\">Size<\/div>\n        <div class=\"list-item download thead\">Download<\/div>\n\n                    <div class=\"list-item name\" data-label=\"Name\">Vitamins and Q10<\/div>\n            <div class=\"list-item rev\" data-label=\"Rev\">214_010_03<\/div>\n            <div class=\"list-item size\" data-label=\"Size\">0.89 MB<\/div>\n            <div class=\"list-item download\" data-label=\"Download\">\n                <a href=\"https:\/\/antecscientific.com\/wp-content\/mu-plugins\/antec-downloads\/files\/apps\/clinical\/214_010_03 - Vitamins and Q10.pdf\" class=\"download-link\" download>Download<i class=\"zmdi zmdi-cloud-download wpfd-download\"><\/i><\/a>\n            <\/div>\n                    <div class=\"list-item name\" data-label=\"Name\">Compilation of Clinical Applications<\/div>\n            <div class=\"list-item rev\" data-label=\"Rev\">214_007_04<\/div>\n            <div class=\"list-item size\" data-label=\"Size\">0.90 MB<\/div>\n            <div class=\"list-item download\" data-label=\"Download\">\n                <a href=\"https:\/\/antecscientific.com\/wp-content\/mu-plugins\/antec-downloads\/files\/apps\/clinical\/214_007_04 - Compilation of Clinical Applications.pdf\" class=\"download-link\" download>Download<i class=\"zmdi zmdi-cloud-download wpfd-download\"><\/i><\/a>\n            <\/div>\n            <\/div>\n\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Download Table&#8221; _builder_version=&#8221;4.27.2&#8243; background_enable_color=&#8221;off&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;#f6f9fb 50%|#ffffff 100%&#8221; background_color_gradient_start=&#8221;#f6f9fb&#8221; background_color_gradient_start_position=&#8221;50%&#8221; background_color_gradient_end=&#8221;#ffffff&#8221; max_width_tablet=&#8221;&#8221; max_width_phone=&#8221;100%&#8221; max_width_last_edited=&#8221;on|desktop&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;0px||0px||false|false&#8221; custom_padding=&#8221;40px||40px||false|false&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; background_color=&#8221;rgba(0,0,0,0)&#8221; width_tablet=&#8221;&#8221; width_phone=&#8221;&#8221; width_last_edited=&#8221;on|phone&#8221; max_width=&#8221;80%&#8221; max_width_tablet=&#8221;&#8221; max_width_phone=&#8221;&#8221; max_width_last_edited=&#8221;on|phone&#8221; module_alignment=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_text admin_label=&#8221;Shortcode of Table&#8221; _builder_version=&#8221;4.16&#8243; background_color=&#8221;#ffffff&#8221; custom_padding=&#8221;20px|30px|30px|30px|false|false&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;|0px||0px|false|false&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_blur=&#8221;40px&#8221; box_shadow_color=&#8221;rgba(0,33,91,0.17)&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>[wpfd_category id=&#8221;21&#8243;]<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vitamine&nbsp; Vitamine liposolubili A, D, E e K Vitamina C nel plasma Q10 e ubiquinoli Doppia cella, per la preriduzione (Vit K, Q10) HyREF senza manutenzione Le vitamine A, D, E e K appartengono alle vitamine liposolubili. Queste vitamine sono coinvolte in diversi processi biochimici dell&#8217;organismo. Anche la vitamina C idrosolubile \u00e8 coinvolta in una [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":16852,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-17621","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vitamine - Antec Scientific<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/antecscientific.com\/it\/applicazioni\/diagnostica\/vitamine\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vitamine - Antec Scientific\" \/>\n<meta property=\"og:description\" content=\"Vitamine&nbsp; Vitamine liposolubili A, D, E e K Vitamina C nel plasma Q10 e ubiquinoli Doppia cella, per la preriduzione (Vit K, Q10) HyREF senza manutenzione Le vitamine A, D, E e K appartengono alle vitamine liposolubili. Queste vitamine sono coinvolte in diversi processi biochimici dell&#039;organismo. Anche la vitamina C idrosolubile \u00e8 coinvolta in una [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/antecscientific.com\/it\/applicazioni\/diagnostica\/vitamine\/\" \/>\n<meta property=\"og:site_name\" content=\"Antec Scientific\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-09T10:49:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/antecscientific.com\\\/it\\\/applicazioni\\\/diagnostica\\\/vitamine\\\/\",\"url\":\"https:\\\/\\\/antecscientific.com\\\/it\\\/applicazioni\\\/diagnostica\\\/vitamine\\\/\",\"name\":\"Vitamine - Antec Scientific\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/antecscientific.com\\\/it\\\/#website\"},\"datePublished\":\"2021-10-02T15:54:47+00:00\",\"dateModified\":\"2025-09-09T10:49:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/antecscientific.com\\\/it\\\/applicazioni\\\/diagnostica\\\/vitamine\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/antecscientific.com\\\/it\\\/applicazioni\\\/diagnostica\\\/vitamine\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/antecscientific.com\\\/it\\\/applicazioni\\\/diagnostica\\\/vitamine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Applicazioni\",\"item\":\"https:\\\/\\\/antecscientific.com\\\/it\\\/applicazioni\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Diagnostica\",\"item\":\"https:\\\/\\\/antecscientific.com\\\/it\\\/applicazioni\\\/diagnostica\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Vitamine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/antecscientific.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/antecscientific.com\\\/it\\\/\",\"name\":\"Antec Scientific\",\"description\":\"Supporting research to improve quality of life\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/antecscientific.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vitamine - Antec Scientific","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/antecscientific.com\/it\/applicazioni\/diagnostica\/vitamine\/","og_locale":"it_IT","og_type":"article","og_title":"Vitamine - Antec Scientific","og_description":"Vitamine&nbsp; Vitamine liposolubili A, D, E e K Vitamina C nel plasma Q10 e ubiquinoli Doppia cella, per la preriduzione (Vit K, Q10) HyREF senza manutenzione Le vitamine A, D, E e K appartengono alle vitamine liposolubili. Queste vitamine sono coinvolte in diversi processi biochimici dell'organismo. Anche la vitamina C idrosolubile \u00e8 coinvolta in una [&hellip;]","og_url":"https:\/\/antecscientific.com\/it\/applicazioni\/diagnostica\/vitamine\/","og_site_name":"Antec Scientific","article_modified_time":"2025-09-09T10:49:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/antecscientific.com\/it\/applicazioni\/diagnostica\/vitamine\/","url":"https:\/\/antecscientific.com\/it\/applicazioni\/diagnostica\/vitamine\/","name":"Vitamine - Antec Scientific","isPartOf":{"@id":"https:\/\/antecscientific.com\/it\/#website"},"datePublished":"2021-10-02T15:54:47+00:00","dateModified":"2025-09-09T10:49:38+00:00","breadcrumb":{"@id":"https:\/\/antecscientific.com\/it\/applicazioni\/diagnostica\/vitamine\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/antecscientific.com\/it\/applicazioni\/diagnostica\/vitamine\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/antecscientific.com\/it\/applicazioni\/diagnostica\/vitamine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Applicazioni","item":"https:\/\/antecscientific.com\/it\/applicazioni\/"},{"@type":"ListItem","position":2,"name":"Diagnostica","item":"https:\/\/antecscientific.com\/it\/applicazioni\/diagnostica\/"},{"@type":"ListItem","position":3,"name":"Vitamine"}]},{"@type":"WebSite","@id":"https:\/\/antecscientific.com\/it\/#website","url":"https:\/\/antecscientific.com\/it\/","name":"Antec Scientific","description":"Supporting research to improve quality of life","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/antecscientific.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/antecscientific.com\/it\/wp-json\/wp\/v2\/pages\/17621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/antecscientific.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/antecscientific.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/antecscientific.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/antecscientific.com\/it\/wp-json\/wp\/v2\/comments?post=17621"}],"version-history":[{"count":6,"href":"https:\/\/antecscientific.com\/it\/wp-json\/wp\/v2\/pages\/17621\/revisions"}],"predecessor-version":[{"id":33423,"href":"https:\/\/antecscientific.com\/it\/wp-json\/wp\/v2\/pages\/17621\/revisions\/33423"}],"up":[{"embeddable":true,"href":"https:\/\/antecscientific.com\/it\/wp-json\/wp\/v2\/pages\/16852"}],"wp:attachment":[{"href":"https:\/\/antecscientific.com\/it\/wp-json\/wp\/v2\/media?parent=17621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}